{"id":7861,"date":"2019-06-27T09:21:56","date_gmt":"2019-06-27T09:21:56","guid":{"rendered":"https:\/\/jumbotours.com\/2019-dates-your-customers-cannot-afford-to-miss\/"},"modified":"2024-02-13T11:49:26","modified_gmt":"2024-02-13T10:49:26","slug":"las-citas-de-2019-que-no-pueden-perderse-tus-clientes","status":"publish","type":"post","link":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/","title":{"rendered":"Las citas de 2019 que no pueden perderse tus clientes"},"content":{"rendered":"<p>Ya estamos a mitad de a\u00f1o, pero los aficionados a vivir experiencias \u00fanicas saben que a\u00fan queda lo mejor por llegar. Desde el inicio del verano y hasta que 2019 llegue a su fin, el calendario est\u00e1 plagado de eventos que son todo un lujo. Disfrutar de esas experiencias es una oportunidad \u00fanica -a veces, literalmente-, motivo m\u00e1s que suficiente para organizar la log\u00edstica con antelaci\u00f3n de forma que nada impida que tus clientes se lo pierdan.<\/p>\n<p>Y es que ante estos eventos es clave anticiparse y reservar tanto entradas como alojamiento y transporte en cuanto sea posible porque, de lo contrario, es muy posible que haya que dejarlo para otra ocasi\u00f3n. Por otra parte, organizar la experiencia completa con tiempo permite tener acceso a mejores precios, una raz\u00f3n m\u00e1s para ser previsores y adelantarse. Estas son algunas de las citas m\u00e1s destacadas de 2019.<\/p>\n<ul>\n<li><strong>Eventos deportivos.<\/strong>\u00a0Hace solo unas semanas que se disputaron encuentros clave como la de la final de la UEFA, pero a\u00fan hay otros muchos eventos deportivos en nuestro calendario. Entre ellos, el tour de Francia, que se celebra del 6 al 28 de julio; el Mundial de Baloncesto, que este a\u00f1o se organiza en China en la primera quincena de septiembre; el famoso marat\u00f3n de Berl\u00edn, que tendr\u00e1 lugar el 29 de septiembre; o la Copa Davis, cuya final se podr\u00e1 ver en la Caja M\u00e1gica de Madrid en noviembre.<\/li>\n<li><strong>Cine, teatro y pintura.<\/strong>\u00a0Este a\u00f1o, el Museo del Prado est\u00e1 de celebraci\u00f3n: se cumplen 200 a\u00f1os desde que abri\u00f3 por primera vez sus puertas. Lo hizo un 19 de noviembre del a\u00f1o 1819, y para celebrarlo ha organizado distintas exposiciones, entre ellas la llamada \u2018Confluencias: Vel\u00e1zquez, Rembrandt, Vermeer y los Siglos de Oro espa\u00f1ol y holand\u00e9s\u2019, \u00a0del 25 de junio al 29 de septiembre, o \u2018S\u00f3lo la voluntad me sobra. Dibujos de Goya\u2019, que se desarrollar\u00e1 del 19 de noviembre al 16 de febrero de 2020. Otras citas interesantes son los festivales de cine de Venecia (del 28 de agosto al 7 de septiembre) y San Sebasti\u00e1n (del 20 al 28 de septiembre), adem\u00e1s del famoso festival de Edimburgo (del 2 al 26 de agosto).<\/li>\n<li><strong>Fiestas.<\/strong>\u00a0La tomatina de Bu\u00f1uel (28 de agosto), el d\u00eda de los muertos de M\u00e9xico (2 de noviembre), el Oktoberfest de Munich (del 21 de septiembre al 6 de octubre), el festival Diwali en India (27 de octubre)\u2026 El calendario est\u00e1 lleno de fiestas tradicionales en cada rinc\u00f3n del mundo, algunas tan especiales que acogen a decenas de miles de visitantes. Son una ocasi\u00f3n perfecta para vivir desde dentro la cultura del lugar.<\/li>\n<li><strong>Conciertos.\u00a0<\/strong>En cuanto a conciertos, cada uno tiene sus \u00eddolos, y verlos sobre el escenario\u00a0 no siempre es posible. Este a\u00f1o est\u00e1n de enhorabuena los seguidores de Elton John, The Smashing Pumpkins, Bon Jovi o Michael Bubbl\u00e9, que se subir\u00e1n a escenarios madrile\u00f1os. Por su parte, Bruno Mars estar\u00e1 en septiembre en Las Vegas, al igual que Lady Gaga, solo que la artista pisar\u00e1 los escenarios de Las Vegas un mes despu\u00e9s.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ya estamos a mitad de a\u00f1o, pero los aficionados a vivir experiencias \u00fanicas saben que a\u00fan queda lo mejor por llegar. Desde el inicio del verano y hasta que 2019 llegue a su fin, el calendario est\u00e1 plagado de eventos que son todo un lujo. Disfrutar de esas experiencias es una oportunidad \u00fanica -a veces, literalmente-, motivo m\u00e1s que suficiente&#8230;<\/p>\n","protected":false},"author":5,"featured_media":7842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","footnotes":""},"categories":[28],"tags":[],"class_list":["post-7861","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cronicas-blog-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las citas de 2019 que no pueden perderse tus clientes | Jumbo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las citas de 2019 que no pueden perderse tus clientes | Jumbo\" \/>\n<meta property=\"og:description\" content=\"Ya estamos a mitad de a\u00f1o, pero los aficionados a vivir experiencias \u00fanicas saben que a\u00fan queda lo mejor por llegar. Desde el inicio del verano y hasta que 2019 llegue a su fin, el calendario est\u00e1 plagado de eventos que son todo un lujo. Disfrutar de esas experiencias es una oportunidad \u00fanica -a veces, literalmente-, motivo m\u00e1s que suficiente...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Jumbo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jumbobeds\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-27T09:21:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-13T10:49:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jumbotours.com\/wp-content\/uploads\/2019\/06\/Tenis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agencia de marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agencia de marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/\"},\"author\":{\"name\":\"Agencia de marketing\",\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#\\\/schema\\\/person\\\/f6cbf368f6492f254804268af16ba8c4\"},\"headline\":\"Las citas de 2019 que no pueden perderse tus clientes\",\"datePublished\":\"2019-06-27T09:21:56+00:00\",\"dateModified\":\"2024-02-13T10:49:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jumbotours.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Tenis.jpg\",\"articleSection\":[\"Cr\u00f3nicas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/\",\"url\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/\",\"name\":\"Las citas de 2019 que no pueden perderse tus clientes | Jumbo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jumbotours.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Tenis.jpg\",\"datePublished\":\"2019-06-27T09:21:56+00:00\",\"dateModified\":\"2024-02-13T10:49:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jumbotours.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Tenis.jpg\",\"contentUrl\":\"https:\\\/\\\/jumbotours.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/Tenis.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las citas de 2019 que no pueden perderse tus clientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#website\",\"url\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/\",\"name\":\"JumboTours\",\"description\":\"Empower your destination.\",\"publisher\":{\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#organization\",\"name\":\"Jumbotours Group\",\"url\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jumbotours.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LogoJTGweb-1.jpg\",\"contentUrl\":\"https:\\\/\\\/jumbotours.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LogoJTGweb-1.jpg\",\"width\":2217,\"height\":2500,\"caption\":\"Jumbotours Group\"},\"image\":{\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jumbobeds\",\"https:\\\/\\\/www.instagram.com\\\/jumbobeds\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/jumbo-tours-espa-a-s-l-\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wwwtest.jumbotours.com\\\/#\\\/schema\\\/person\\\/f6cbf368f6492f254804268af16ba8c4\",\"name\":\"Agencia de marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1237bfb3f4879df84c460da7d69e6795d4c3cf4f472c379a0cff3fd6affcf435?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1237bfb3f4879df84c460da7d69e6795d4c3cf4f472c379a0cff3fd6affcf435?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1237bfb3f4879df84c460da7d69e6795d4c3cf4f472c379a0cff3fd6affcf435?s=96&d=mm&r=g\",\"caption\":\"Agencia de marketing\"},\"sameAs\":[\"https:\\\/\\\/zinkmarketing.es\\\/\"],\"url\":\"https:\\\/\\\/jumbotours.com\\\/es\\\/author\\\/zink-marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las citas de 2019 que no pueden perderse tus clientes | Jumbo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/","og_locale":"es_ES","og_type":"article","og_title":"Las citas de 2019 que no pueden perderse tus clientes | Jumbo","og_description":"Ya estamos a mitad de a\u00f1o, pero los aficionados a vivir experiencias \u00fanicas saben que a\u00fan queda lo mejor por llegar. Desde el inicio del verano y hasta que 2019 llegue a su fin, el calendario est\u00e1 plagado de eventos que son todo un lujo. Disfrutar de esas experiencias es una oportunidad \u00fanica -a veces, literalmente-, motivo m\u00e1s que suficiente...","og_url":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/","og_site_name":"Jumbo","article_publisher":"https:\/\/www.facebook.com\/jumbobeds","article_published_time":"2019-06-27T09:21:56+00:00","article_modified_time":"2024-02-13T10:49:26+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/jumbotours.com\/wp-content\/uploads\/2019\/06\/Tenis.jpg","type":"image\/jpeg"}],"author":"Agencia de marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Agencia de marketing","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/#article","isPartOf":{"@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/"},"author":{"name":"Agencia de marketing","@id":"https:\/\/wwwtest.jumbotours.com\/#\/schema\/person\/f6cbf368f6492f254804268af16ba8c4"},"headline":"Las citas de 2019 que no pueden perderse tus clientes","datePublished":"2019-06-27T09:21:56+00:00","dateModified":"2024-02-13T10:49:26+00:00","mainEntityOfPage":{"@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/"},"wordCount":525,"publisher":{"@id":"https:\/\/wwwtest.jumbotours.com\/#organization"},"image":{"@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/jumbotours.com\/wp-content\/uploads\/2019\/06\/Tenis.jpg","articleSection":["Cr\u00f3nicas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/","url":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/","name":"Las citas de 2019 que no pueden perderse tus clientes | Jumbo","isPartOf":{"@id":"https:\/\/wwwtest.jumbotours.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/#primaryimage"},"image":{"@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/jumbotours.com\/wp-content\/uploads\/2019\/06\/Tenis.jpg","datePublished":"2019-06-27T09:21:56+00:00","dateModified":"2024-02-13T10:49:26+00:00","breadcrumb":{"@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/#primaryimage","url":"https:\/\/jumbotours.com\/wp-content\/uploads\/2019\/06\/Tenis.jpg","contentUrl":"https:\/\/jumbotours.com\/wp-content\/uploads\/2019\/06\/Tenis.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/jumbotours.com\/es\/las-citas-de-2019-que-no-pueden-perderse-tus-clientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jumbotours.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las citas de 2019 que no pueden perderse tus clientes"}]},{"@type":"WebSite","@id":"https:\/\/wwwtest.jumbotours.com\/#website","url":"https:\/\/wwwtest.jumbotours.com\/","name":"JumboTours","description":"Empower your destination.","publisher":{"@id":"https:\/\/wwwtest.jumbotours.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wwwtest.jumbotours.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wwwtest.jumbotours.com\/#organization","name":"Jumbotours Group","url":"https:\/\/wwwtest.jumbotours.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wwwtest.jumbotours.com\/#\/schema\/logo\/image\/","url":"https:\/\/jumbotours.com\/wp-content\/uploads\/2020\/03\/LogoJTGweb-1.jpg","contentUrl":"https:\/\/jumbotours.com\/wp-content\/uploads\/2020\/03\/LogoJTGweb-1.jpg","width":2217,"height":2500,"caption":"Jumbotours Group"},"image":{"@id":"https:\/\/wwwtest.jumbotours.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/jumbobeds","https:\/\/www.instagram.com\/jumbobeds\/","https:\/\/www.linkedin.com\/company\/jumbo-tours-espa-a-s-l-\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/wwwtest.jumbotours.com\/#\/schema\/person\/f6cbf368f6492f254804268af16ba8c4","name":"Agencia de marketing","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1237bfb3f4879df84c460da7d69e6795d4c3cf4f472c379a0cff3fd6affcf435?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1237bfb3f4879df84c460da7d69e6795d4c3cf4f472c379a0cff3fd6affcf435?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1237bfb3f4879df84c460da7d69e6795d4c3cf4f472c379a0cff3fd6affcf435?s=96&d=mm&r=g","caption":"Agencia de marketing"},"sameAs":["https:\/\/zinkmarketing.es\/"],"url":"https:\/\/jumbotours.com\/es\/author\/zink-marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/posts\/7861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/comments?post=7861"}],"version-history":[{"count":3,"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/posts\/7861\/revisions"}],"predecessor-version":[{"id":7864,"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/posts\/7861\/revisions\/7864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/media\/7842"}],"wp:attachment":[{"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/media?parent=7861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/categories?post=7861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jumbotours.com\/es\/wp-json\/wp\/v2\/tags?post=7861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}